{"id":53445,"date":"2025-02-13T15:47:19","date_gmt":"2025-02-13T21:47:19","guid":{"rendered":"https:\/\/amccimexico.com\/lg2\/?post_type=ejemplares&#038;p=53445"},"modified":"2025-02-13T16:06:28","modified_gmt":"2025-02-13T22:06:28","slug":"mariana-jb","status":"publish","type":"ejemplares","link":"https:\/\/amccimexico.com\/lg2\/ejemplares\/mariana-jb\/","title":{"rendered":"MARIANA JB"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]AMCCI es la Asociaci\u00f3n oficialmente reconocida para la gesti\u00f3n del Libro Geneal\u00f3gico del caballo Iberoamericano en M\u00e9xico.<br \/>\nEl LG-AMCCI es el organismo emisor de los Documentos de Identificaci\u00f3n Equina de los ejemplares de la raza Iberoamericana en M\u00e9xico. El documento a descargar no cuenta con ninguna validez notarial o legal. El contenido de la p\u00e1gina web, im\u00e1genes, textos y datos, son propiedad de AMCCI M\u00e9xico as\u00ed como su c\u00f3digo fuente, dise\u00f1o y estructura de navegaci\u00f3n. Corresponde a AMCCI M\u00e9xico el ejercicio exclusivo de los derechos de explotaci\u00f3n de los mismos en cualquier forma, y en especial los derechos de reproducci\u00f3n, distribuci\u00f3n, comunicaci\u00f3n p\u00fablica y transformaci\u00f3n. Todo este material est\u00e1 protegido por la legislaci\u00f3n de la propiedad intelectual y su uso indebido puede ser objeto de sanciones, incluso penales. <strong>Autorizaciones. <\/strong>Todos los art\u00edculos, publicaciones, libros, revistas o similares con el s\u00edmbolo <strong>\u00a9 y la referencia Copyright AMCCI M\u00e9xico <\/strong><em><strong>.<\/strong><\/em><strong><em> Todos los derechos reservados<\/em><\/strong>son propiedad de AMCCI M\u00e9xico siendo necesario el consentimiento expreso y por escrito de \u00e9ste para su utilizaci\u00f3n y divulgaci\u00f3n, ya sea parcial o total de los referidos contenidos. AMCCI M\u00e9xico se reserva los derechos de autor de la informaci\u00f3n presentada en este sitio de Internet, salvo que se indique otra cosa; tambi\u00e9n deben respetarse los derechos de autor del material de terceros que aparece. Puede solicitar autorizaci\u00f3n para reproducir el material de AMCCI M\u00e9xico disponible en este sitio Web. <strong>Publicaciones, art\u00edculos, ensayos, revistas, libros, comentarios y similares.<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_empty_space height=&#8221;62px&#8221;][vc_column_text]<iframe onload=\"e2pdfViewer.iframeLoad(this)\" name=\"a3acb30a8487b680eb5e1f4240028751\" style=\"\" class=\"e2pdf-view e2pdf-dark-theme\"  width=\"100%\" height=\"500\" src=\"https:\/\/amccimexico.com\/lg2\/wp-content\/plugins\/e2pdf\/assets\/pdf.js\/web\/viewer.html?file=https%3A%2F%2Famccimexico.com%2Flg2%2F%3Fpage%3De2pdf-download%26uid%3D798cb71d33324539d7f54607e019947b%26v%3D1.32.43%26saveName%3Dejemplares.pdf\"><\/iframe>[\/vc_column_text][vc_empty_space height=&#8221;62px&#8221;][vc_column_text][privado]<\/p>\n<iframe onload=\"e2pdfViewer.iframeLoad(this)\" name=\"a3acb30a8487b680eb5e1f4240028751\" style=\"\" class=\"e2pdf-view e2pdf-dark-theme\"  width=\"100%\" height=\"500\" src=\"https:\/\/amccimexico.com\/lg2\/wp-content\/plugins\/e2pdf\/assets\/pdf.js\/web\/viewer.html?file=https%3A%2F%2Famccimexico.com%2Flg2%2F%3Fpage%3De2pdf-download%26uid%3D5c6e82f44b62fa6105a1d47cc13d1db9%26v%3D1.32.43%26saveName%3Dregistro%2520impresion.pdf\"><\/iframe>\n<p>[\/privado][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"template":"","format":"standard","meta":{"_acf_changed":false},"propietarios":[95],"criadores":[96],"semental":[],"campeonatos":[],"clase":[],"titulares":[569],"class_list":["post-53445","ejemplares","type-ejemplares","status-publish","format-standard","hentry","propietarios-rancho-el-rebozo","criadores-rancho-el-rebozo","titular-rancho-el-rebozo"],"acf":[],"_links":{"self":[{"href":"https:\/\/amccimexico.com\/lg2\/wp-json\/wp\/v2\/ejemplares\/53445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amccimexico.com\/lg2\/wp-json\/wp\/v2\/ejemplares"}],"about":[{"href":"https:\/\/amccimexico.com\/lg2\/wp-json\/wp\/v2\/types\/ejemplares"}],"author":[{"embeddable":true,"href":"https:\/\/amccimexico.com\/lg2\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/amccimexico.com\/lg2\/wp-json\/wp\/v2\/media?parent=53445"}],"wp:term":[{"taxonomy":"propietarios","embeddable":true,"href":"https:\/\/amccimexico.com\/lg2\/wp-json\/wp\/v2\/propietarios?post=53445"},{"taxonomy":"criadores","embeddable":true,"href":"https:\/\/amccimexico.com\/lg2\/wp-json\/wp\/v2\/criadores?post=53445"},{"taxonomy":"semental","embeddable":true,"href":"https:\/\/amccimexico.com\/lg2\/wp-json\/wp\/v2\/semental?post=53445"},{"taxonomy":"campeonatos","embeddable":true,"href":"https:\/\/amccimexico.com\/lg2\/wp-json\/wp\/v2\/campeonatos?post=53445"},{"taxonomy":"clase_individual","embeddable":true,"href":"https:\/\/amccimexico.com\/lg2\/wp-json\/wp\/v2\/clase?post=53445"},{"taxonomy":"titular","embeddable":true,"href":"https:\/\/amccimexico.com\/lg2\/wp-json\/wp\/v2\/titulares?post=53445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}